{"id":2,"date":"2024-06-19T08:49:24","date_gmt":"2024-06-19T08:49:24","guid":{"rendered":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/?page_id=2"},"modified":"2026-08-12T14:24:07","modified_gmt":"2026-08-12T14:24:07","slug":"casa","status":"publish","type":"page","link":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/casa\/","title":{"rendered":"The house"},"content":{"rendered":"<p>The <strong>Casa dos Arcos<\/strong> is a welcoming and bright single-story house, located in a quiet area of \u200b\u200bVilamoura, ideal for those seeking comfort, privacy, and a relaxed atmosphere. With three bedrooms, spacious areas, and a harmonious connection between interior and exterior, the house was designed to provide a relaxing stay, whether with family or friends.<\/p>\n<p>The spacious and comfortable living room connects directly to the garden, creating a sense of continuity and allowing you to enjoy natural light throughout the day. The fully equipped kitchen offers all the necessary amenities for preparing meals with ease, while the bedrooms ensure rest and functionality, with options for different types of occupancy.<\/p>\n<p>Outside, the house stands out for its private pool, spacious garden, and shaded areas perfect for al fresco dining. The serene atmosphere, surrounded by mature vegetation, conveys a sense of refuge while maintaining proximity to Vilamoura Marina, beaches, shops, and services. Casa dos Arcos combines the charm of a traditional house with modern comfort, making it the ideal starting point to enjoy the Algarve in tranquility.<\/p>","protected":false},"excerpt":{"rendered":"<p>A Casa dos Arcos \u00e9 uma moradia t\u00e9rrea acolhedora e luminosa, situada numa zona tranquila de Vilamoura, ideal para quem procura conforto, privacidade e um ambiente descontra\u00eddo. Com tr\u00eas quartos, \u00e1reas amplas e uma liga\u00e7\u00e3o harmoniosa entre interior e exterior, a casa foi pensada para proporcionar uma estadia relaxada, seja em fam\u00edlia ou entre amigos. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2547,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"page-casa.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A casa - Casa dos Arcos<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A casa - Casa dos Arcos\" \/>\n<meta property=\"og:description\" content=\"A Casa dos Arcos \u00e9 uma moradia t\u00e9rrea acolhedora e luminosa, situada numa zona tranquila de Vilamoura, ideal para quem procura conforto, privacidade e um ambiente descontra\u00eddo. Com tr\u00eas quartos, \u00e1reas amplas e uma liga\u00e7\u00e3o harmoniosa entre interior e exterior, a casa foi pensada para proporcionar uma estadia relaxada, seja em fam\u00edlia ou entre amigos. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa dos Arcos\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T14:24:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/\",\"url\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/\",\"name\":\"A casa - Casa dos Arcos\",\"isPartOf\":{\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp\",\"datePublished\":\"2024-06-19T08:49:24+00:00\",\"dateModified\":\"2026-08-12T14:24:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#primaryimage\",\"url\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp\",\"contentUrl\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp\",\"width\":1400,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#website\",\"url\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/\",\"name\":\"Casa dos Arcos\",\"description\":\"Tranquilidade\",\"publisher\":{\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#organization\",\"name\":\"Casa dos Arcos\",\"url\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/08\/cropped-logo.jpg\",\"contentUrl\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/08\/cropped-logo.jpg\",\"width\":1278,\"height\":452,\"caption\":\"Casa dos Arcos\"},\"image\":{\"@id\":\"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A casa - Casa dos Arcos","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"A casa - Casa dos Arcos","og_description":"A Casa dos Arcos \u00e9 uma moradia t\u00e9rrea acolhedora e luminosa, situada numa zona tranquila de Vilamoura, ideal para quem procura conforto, privacidade e um ambiente descontra\u00eddo. Com tr\u00eas quartos, \u00e1reas amplas e uma liga\u00e7\u00e3o harmoniosa entre interior e exterior, a casa foi pensada para proporcionar uma estadia relaxada, seja em fam\u00edlia ou entre amigos. [&hellip;]","og_url":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/casa\/","og_site_name":"Casa dos Arcos","article_modified_time":"2026-08-12T14:24:07+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/","url":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/","name":"A casa - Casa dos Arcos","isPartOf":{"@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#primaryimage"},"image":{"@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#primaryimage"},"thumbnailUrl":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp","datePublished":"2024-06-19T08:49:24+00:00","dateModified":"2026-08-12T14:24:07+00:00","breadcrumb":{"@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#primaryimage","url":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp","contentUrl":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/07\/casa-dos-arcos-vilamoura-entrada-estacionamento.webp","width":1400,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/"},{"@type":"ListItem","position":2,"name":"A casa"}]},{"@type":"WebSite","@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#website","url":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/","name":"Casa dos Arcos","description":"Peace of Mind","publisher":{"@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#organization","name":"Casa dos Arcos","url":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#\/schema\/logo\/image\/","url":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/08\/cropped-logo.jpg","contentUrl":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/wp-content\/uploads\/2026\/08\/cropped-logo.jpg","width":1278,"height":452,"caption":"Casa dos Arcos"},"image":{"@id":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":107,"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":2565,"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/pages\/2\/revisions\/2565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/media\/2547"}],"wp:attachment":[{"href":"https:\/\/casadosarcos-vilamoura.celeumasandbox.pt\/en\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}